{"id":14594,"date":"2014-11-02T22:03:53","date_gmt":"2014-11-02T22:03:53","guid":{"rendered":"http:\/\/www.unsponsored.co.uk:\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2.jpg"},"modified":"2014-11-02T22:03:53","modified_gmt":"2014-11-02T22:03:53","slug":"unsponsored_gopro_frame2","status":"inherit","type":"attachment","link":"https:\/\/www.unsponsored.co.uk\/press\/gopro-the-frame-mount-review\/unsponsored_gopro_frame2\/","title":{"rendered":"Unsponsored_GoPro_frame2"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-14594","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unsponsored_GoPro_frame2 - Unsponsored<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unsponsored_GoPro_frame2 - Unsponsored\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Unsponsored\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/Unsponsored_GoPro_frame2.jpg\",\"url\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/Unsponsored_GoPro_frame2.jpg\",\"name\":\"Unsponsored_GoPro_frame2 - Unsponsored\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#website\"},\"datePublished\":\"2014-11-02T22:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/Unsponsored_GoPro_frame2.jpg#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/Unsponsored_GoPro_frame2.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/Unsponsored_GoPro_frame2.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GoPro The Frame Mount &#8211; Review\",\"item\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/gopro-the-frame-mount-review\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Unsponsored_GoPro_frame2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#website\",\"url\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/\",\"name\":\"Unsponsored\",\"description\":\"Paddling tips, tricks, news and gear reviews from an Unsponsored point of view\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#\\\/schema\\\/person\\\/ce92703784b5b380a7ccd2c12e0231a5\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#\\\/schema\\\/person\\\/ce92703784b5b380a7ccd2c12e0231a5\",\"name\":\"Unsponsored\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Viking-Banner-e1771869893655.png\",\"url\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Viking-Banner-e1771869893655.png\",\"contentUrl\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Viking-Banner-e1771869893655.png\",\"width\":163,\"height\":177,\"caption\":\"Unsponsored\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Viking-Banner-e1771869893655.png\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unsponsored_GoPro_frame2 - Unsponsored","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2.jpg","og_locale":"en_GB","og_type":"article","og_title":"Unsponsored_GoPro_frame2 - Unsponsored","og_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2.jpg","og_site_name":"Unsponsored","og_image":[{"width":960,"height":720,"url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2.jpg","url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2.jpg","name":"Unsponsored_GoPro_frame2 - Unsponsored","isPartOf":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/#website"},"datePublished":"2014-11-02T22:03:53+00:00","breadcrumb":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2.jpg#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unsponsored.co.uk\/press\/"},{"@type":"ListItem","position":2,"name":"GoPro The Frame Mount &#8211; Review","item":"https:\/\/www.unsponsored.co.uk\/press\/gopro-the-frame-mount-review\/"},{"@type":"ListItem","position":3,"name":"Unsponsored_GoPro_frame2"}]},{"@type":"WebSite","@id":"https:\/\/www.unsponsored.co.uk\/press\/#website","url":"https:\/\/www.unsponsored.co.uk\/press\/","name":"Unsponsored","description":"Paddling tips, tricks, news and gear reviews from an Unsponsored point of view","publisher":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/#\/schema\/person\/ce92703784b5b380a7ccd2c12e0231a5"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unsponsored.co.uk\/press\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/www.unsponsored.co.uk\/press\/#\/schema\/person\/ce92703784b5b380a7ccd2c12e0231a5","name":"Unsponsored","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2020\/03\/Viking-Banner-e1771869893655.png","url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2020\/03\/Viking-Banner-e1771869893655.png","contentUrl":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2020\/03\/Viking-Banner-e1771869893655.png","width":163,"height":177,"caption":"Unsponsored"},"logo":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2020\/03\/Viking-Banner-e1771869893655.png"}}]}},"jetpack_shortlink":"https:\/\/wp.me\/a2ugbA-3No","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2-300x225.jpg 300w, https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"14594\" data-permalink=\"https:\/\/www.unsponsored.co.uk\/press\/gopro-the-frame-mount-review\/unsponsored_gopro_frame2\/\" data-orig-file=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2.jpg\" data-orig-size=\"960,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Unsponsored_GoPro_frame2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2.jpg\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":960,"height":720,"file":"2014\/11\/Unsponsored_GoPro_frame2.jpg","sizes":{"thumbnail":{"file":"Unsponsored_GoPro_frame2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2-150x150.jpg"},"medium":{"file":"Unsponsored_GoPro_frame2-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2-300x225.jpg"},"post-thumbnail":{"file":"Unsponsored_GoPro_frame2-672x372.jpg","width":672,"height":372,"mime_type":"image\/jpeg","source_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2-672x372.jpg"},"twentyfourteen-full-width":{"file":"Unsponsored_GoPro_frame2-960x576.jpg","width":960,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2-960x576.jpg"},"full":{"file":"Unsponsored_GoPro_frame2.jpg","width":960,"height":720,"mime_type":"image\/jpeg","source_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":14592,"source_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2014\/11\/Unsponsored_GoPro_frame2.jpg","filename":"Unsponsored_GoPro_frame2.jpg","filesize":121098,"_links":{"self":[{"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/media\/14594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/comments?post=14594"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":14592,"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/posts\/14592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}