{"id":18797,"date":"2015-09-01T19:54:36","date_gmt":"2015-09-01T18:54:36","guid":{"rendered":"http:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA.png"},"modified":"2015-09-01T19:54:58","modified_gmt":"2015-09-01T18:54:58","slug":"unsponsored-qa","status":"inherit","type":"attachment","link":"https:\/\/www.unsponsored.co.uk\/press\/unsponsored-qa-david-turnbull\/unsponsored-qa\/","title":{"rendered":"Unsponsored Q&#038;A &#8211; David Turnbull"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-18797","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unsponsored Q&amp;A - David Turnbull - Unsponsored<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA.png\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unsponsored Q&amp;A - David Turnbull - Unsponsored\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA.png\" \/>\n<meta property=\"og:site_name\" content=\"Unsponsored\" \/>\n<meta property=\"article:modified_time\" content=\"2015-09-01T18:54:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA.png\" \/>\n\t<meta property=\"og:image:width\" content=\"579\" \/>\n\t<meta property=\"og:image:height\" content=\"453\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/Unsponsored-QA.png\",\"url\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/Unsponsored-QA.png\",\"name\":\"Unsponsored Q&A - David Turnbull - Unsponsored\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#website\"},\"datePublished\":\"2015-09-01T18:54:36+00:00\",\"dateModified\":\"2015-09-01T18:54:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/Unsponsored-QA.png#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/Unsponsored-QA.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/Unsponsored-QA.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unsponsored Q&#038;A Series &#8211; David Turnbull\",\"item\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/unsponsored-qa-david-turnbull\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Unsponsored Q&#038;A &#8211; David Turnbull\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#website\",\"url\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/\",\"name\":\"Unsponsored\",\"description\":\"Paddling tips, tricks, news and gear reviews from an Unsponsored point of view\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#\\\/schema\\\/person\\\/ce92703784b5b380a7ccd2c12e0231a5\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#\\\/schema\\\/person\\\/ce92703784b5b380a7ccd2c12e0231a5\",\"name\":\"Unsponsored\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Viking-Banner-e1771869893655.png\",\"url\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Viking-Banner-e1771869893655.png\",\"contentUrl\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Viking-Banner-e1771869893655.png\",\"width\":163,\"height\":177,\"caption\":\"Unsponsored\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Viking-Banner-e1771869893655.png\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unsponsored Q&A - David Turnbull - Unsponsored","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA.png","og_locale":"en_GB","og_type":"article","og_title":"Unsponsored Q&A - David Turnbull - Unsponsored","og_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA.png","og_site_name":"Unsponsored","article_modified_time":"2015-09-01T18:54:58+00:00","og_image":[{"width":579,"height":453,"url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA.png","url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA.png","name":"Unsponsored Q&A - David Turnbull - Unsponsored","isPartOf":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/#website"},"datePublished":"2015-09-01T18:54:36+00:00","dateModified":"2015-09-01T18:54:58+00:00","breadcrumb":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA.png#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unsponsored.co.uk\/press\/"},{"@type":"ListItem","position":2,"name":"Unsponsored Q&#038;A Series &#8211; David Turnbull","item":"https:\/\/www.unsponsored.co.uk\/press\/unsponsored-qa-david-turnbull\/"},{"@type":"ListItem","position":3,"name":"Unsponsored Q&#038;A &#8211; David Turnbull"}]},{"@type":"WebSite","@id":"https:\/\/www.unsponsored.co.uk\/press\/#website","url":"https:\/\/www.unsponsored.co.uk\/press\/","name":"Unsponsored","description":"Paddling tips, tricks, news and gear reviews from an Unsponsored point of view","publisher":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/#\/schema\/person\/ce92703784b5b380a7ccd2c12e0231a5"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unsponsored.co.uk\/press\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/www.unsponsored.co.uk\/press\/#\/schema\/person\/ce92703784b5b380a7ccd2c12e0231a5","name":"Unsponsored","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2020\/03\/Viking-Banner-e1771869893655.png","url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2020\/03\/Viking-Banner-e1771869893655.png","contentUrl":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2020\/03\/Viking-Banner-e1771869893655.png","width":163,"height":177,"caption":"Unsponsored"},"logo":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2020\/03\/Viking-Banner-e1771869893655.png"}}]}},"jetpack_shortlink":"https:\/\/wp.me\/a2ugbA-4Tb","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"235\" src=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA-300x235.png\" class=\"attachment-medium size-medium\" alt=\"Unsponsored Q&amp;A - David Turnbull\" srcset=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA-300x235.png 300w, https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA.png 579w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"18797\" data-permalink=\"https:\/\/www.unsponsored.co.uk\/press\/unsponsored-qa-david-turnbull\/unsponsored-qa\/\" data-orig-file=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA.png\" data-orig-size=\"579,453\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Unsponsored Q&amp;#038;A &amp;#8211; David Turnbull\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA.png\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Unsponsored Q&A - David Turnbull","media_type":"image","mime_type":"image\/png","media_details":{"width":579,"height":453,"file":"2015\/09\/Unsponsored-QA.png","sizes":{"thumbnail":{"file":"Unsponsored-QA-200x200.png","width":200,"height":200,"mime_type":"image\/png","source_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA-200x200.png"},"medium":{"file":"Unsponsored-QA-300x235.png","width":300,"height":235,"mime_type":"image\/png","source_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA-300x235.png"},"full":{"file":"Unsponsored-QA.png","width":579,"height":453,"mime_type":"image\/png","source_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA.png"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":18777,"source_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/09\/Unsponsored-QA.png","filename":"Unsponsored-QA.png","filesize":651378,"_links":{"self":[{"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/media\/18797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/comments?post=18797"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":18777,"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/posts\/18777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}