{"id":20378,"date":"2015-11-25T20:13:55","date_gmt":"2015-11-25T20:13:55","guid":{"rendered":"http:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n.jpg"},"modified":"2015-11-25T20:14:00","modified_gmt":"2015-11-25T20:14:00","slug":"12294805_559522594198636_4669946884703130587_n","status":"inherit","type":"attachment","link":"https:\/\/www.unsponsored.co.uk\/press\/hurley-classic-2015-day-2\/12294805_559522594198636_4669946884703130587_n\/","title":{"rendered":"Hurley Classic 2015 &#8211; Day 2"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-20378","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hurley Classic 2015 - Day 2 - Unsponsored<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hurley Classic 2015 - Day 2 - Unsponsored\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Unsponsored\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-25T20:14:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"639\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/12294805_559522594198636_4669946884703130587_n.jpg\",\"url\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/12294805_559522594198636_4669946884703130587_n.jpg\",\"name\":\"Hurley Classic 2015 - Day 2 - Unsponsored\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#website\"},\"datePublished\":\"2015-11-25T20:13:55+00:00\",\"dateModified\":\"2015-11-25T20:14:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/12294805_559522594198636_4669946884703130587_n.jpg#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/12294805_559522594198636_4669946884703130587_n.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/12294805_559522594198636_4669946884703130587_n.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hurley Classic 2015 &#8211; Day 2\",\"item\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/hurley-classic-2015-day-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hurley Classic 2015 &#8211; Day 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#website\",\"url\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/\",\"name\":\"Unsponsored\",\"description\":\"Paddling tips, tricks, news and gear reviews from an Unsponsored point of view\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#\\\/schema\\\/person\\\/ce92703784b5b380a7ccd2c12e0231a5\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#\\\/schema\\\/person\\\/ce92703784b5b380a7ccd2c12e0231a5\",\"name\":\"Unsponsored\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Viking-Banner-e1771869893655.png\",\"url\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Viking-Banner-e1771869893655.png\",\"contentUrl\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Viking-Banner-e1771869893655.png\",\"width\":163,\"height\":177,\"caption\":\"Unsponsored\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Viking-Banner-e1771869893655.png\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hurley Classic 2015 - Day 2 - Unsponsored","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n.jpg","og_locale":"en_GB","og_type":"article","og_title":"Hurley Classic 2015 - Day 2 - Unsponsored","og_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n.jpg","og_site_name":"Unsponsored","article_modified_time":"2015-11-25T20:14:00+00:00","og_image":[{"width":960,"height":639,"url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n.jpg","url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n.jpg","name":"Hurley Classic 2015 - Day 2 - Unsponsored","isPartOf":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/#website"},"datePublished":"2015-11-25T20:13:55+00:00","dateModified":"2015-11-25T20:14:00+00:00","breadcrumb":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n.jpg#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unsponsored.co.uk\/press\/"},{"@type":"ListItem","position":2,"name":"Hurley Classic 2015 &#8211; Day 2","item":"https:\/\/www.unsponsored.co.uk\/press\/hurley-classic-2015-day-2\/"},{"@type":"ListItem","position":3,"name":"Hurley Classic 2015 &#8211; Day 2"}]},{"@type":"WebSite","@id":"https:\/\/www.unsponsored.co.uk\/press\/#website","url":"https:\/\/www.unsponsored.co.uk\/press\/","name":"Unsponsored","description":"Paddling tips, tricks, news and gear reviews from an Unsponsored point of view","publisher":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/#\/schema\/person\/ce92703784b5b380a7ccd2c12e0231a5"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unsponsored.co.uk\/press\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/www.unsponsored.co.uk\/press\/#\/schema\/person\/ce92703784b5b380a7ccd2c12e0231a5","name":"Unsponsored","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2020\/03\/Viking-Banner-e1771869893655.png","url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2020\/03\/Viking-Banner-e1771869893655.png","contentUrl":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2020\/03\/Viking-Banner-e1771869893655.png","width":163,"height":177,"caption":"Unsponsored"},"logo":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2020\/03\/Viking-Banner-e1771869893655.png"}}]}},"jetpack_shortlink":"https:\/\/wp.me\/a2ugbA-5iG","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"Hurley Classic 2015 - Day 2\" srcset=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n-300x200.jpg 300w, https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n-676x450.jpg 676w, https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"20378\" data-permalink=\"https:\/\/www.unsponsored.co.uk\/press\/hurley-classic-2015-day-2\/12294805_559522594198636_4669946884703130587_n\/\" data-orig-file=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n.jpg\" data-orig-size=\"960,639\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Jack Gunter&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;Jack Gunter&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Hurley Classic 2015 &amp;#8211; Day 2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n.jpg\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Hurley Classic 2015 - Day 2","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":960,"height":639,"file":"2015\/11\/12294805_559522594198636_4669946884703130587_n.jpg","sizes":{"thumbnail":{"file":"12294805_559522594198636_4669946884703130587_n-200x200.jpg","width":200,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n-200x200.jpg"},"medium":{"file":"12294805_559522594198636_4669946884703130587_n-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n-300x200.jpg"},"post-image":{"file":"12294805_559522594198636_4669946884703130587_n-676x450.jpg","width":676,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n-676x450.jpg"},"full":{"file":"12294805_559522594198636_4669946884703130587_n.jpg","width":960,"height":639,"mime_type":"image\/jpeg","source_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n.jpg"}},"image_meta":{"aperture":0,"credit":"Jack Gunter","camera":"","caption":"","created_timestamp":0,"copyright":"Jack Gunter","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":20370,"source_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2015\/11\/12294805_559522594198636_4669946884703130587_n.jpg","filename":"12294805_559522594198636_4669946884703130587_n.jpg","filesize":128655,"_links":{"self":[{"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/media\/20378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/comments?post=20378"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":20370,"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/posts\/20370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}