{"id":23639,"date":"2016-10-26T14:38:57","date_gmt":"2016-10-26T13:38:57","guid":{"rendered":"http:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1.jpg"},"modified":"2016-10-26T14:38:57","modified_gmt":"2016-10-26T13:38:57","slug":"unsponsored-rescue-essentials-2-1","status":"inherit","type":"attachment","link":"https:\/\/www.unsponsored.co.uk\/press\/rescue-essentials-2\/unsponsored-rescue-essentials-2-1\/","title":{"rendered":"unsponsored-rescue-essentials-2-1"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-23639","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>unsponsored-rescue-essentials-2-1 - Unsponsored<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"unsponsored-rescue-essentials-2-1 - Unsponsored\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Unsponsored\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Unsponsored-Rescue-Essentials-2-1.jpg\",\"url\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Unsponsored-Rescue-Essentials-2-1.jpg\",\"name\":\"unsponsored-rescue-essentials-2-1 - Unsponsored\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#website\"},\"datePublished\":\"2016-10-26T13:38:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Unsponsored-Rescue-Essentials-2-1.jpg#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Unsponsored-Rescue-Essentials-2-1.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Unsponsored-Rescue-Essentials-2-1.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rescue Essentials\",\"item\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/rescue-essentials-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"unsponsored-rescue-essentials-2-1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#website\",\"url\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/\",\"name\":\"Unsponsored\",\"description\":\"Paddling tips, tricks, news and gear reviews from an Unsponsored point of view\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#\\\/schema\\\/person\\\/ce92703784b5b380a7ccd2c12e0231a5\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#\\\/schema\\\/person\\\/ce92703784b5b380a7ccd2c12e0231a5\",\"name\":\"Unsponsored\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Viking-Banner-e1771869893655.png\",\"url\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Viking-Banner-e1771869893655.png\",\"contentUrl\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Viking-Banner-e1771869893655.png\",\"width\":163,\"height\":177,\"caption\":\"Unsponsored\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Viking-Banner-e1771869893655.png\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"unsponsored-rescue-essentials-2-1 - Unsponsored","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1.jpg","og_locale":"en_GB","og_type":"article","og_title":"unsponsored-rescue-essentials-2-1 - Unsponsored","og_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1.jpg","og_site_name":"Unsponsored","og_image":[{"width":480,"height":640,"url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1.jpg","url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1.jpg","name":"unsponsored-rescue-essentials-2-1 - Unsponsored","isPartOf":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/#website"},"datePublished":"2016-10-26T13:38:57+00:00","breadcrumb":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1.jpg#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unsponsored.co.uk\/press\/"},{"@type":"ListItem","position":2,"name":"Rescue Essentials","item":"https:\/\/www.unsponsored.co.uk\/press\/rescue-essentials-2\/"},{"@type":"ListItem","position":3,"name":"unsponsored-rescue-essentials-2-1"}]},{"@type":"WebSite","@id":"https:\/\/www.unsponsored.co.uk\/press\/#website","url":"https:\/\/www.unsponsored.co.uk\/press\/","name":"Unsponsored","description":"Paddling tips, tricks, news and gear reviews from an Unsponsored point of view","publisher":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/#\/schema\/person\/ce92703784b5b380a7ccd2c12e0231a5"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unsponsored.co.uk\/press\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/www.unsponsored.co.uk\/press\/#\/schema\/person\/ce92703784b5b380a7ccd2c12e0231a5","name":"Unsponsored","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2020\/03\/Viking-Banner-e1771869893655.png","url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2020\/03\/Viking-Banner-e1771869893655.png","contentUrl":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2020\/03\/Viking-Banner-e1771869893655.png","width":163,"height":177,"caption":"Unsponsored"},"logo":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2020\/03\/Viking-Banner-e1771869893655.png"}}]}},"jetpack_shortlink":"https:\/\/wp.me\/a2ugbA-69h","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1-225x300.jpg 225w, https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1.jpg 480w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" data-attachment-id=\"23639\" data-permalink=\"https:\/\/www.unsponsored.co.uk\/press\/rescue-essentials-2\/unsponsored-rescue-essentials-2-1\/\" data-orig-file=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1.jpg\" data-orig-size=\"480,640\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 6s&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1456746717&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.15&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.013888888888889&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"unsponsored-rescue-essentials-2-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1.jpg\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":480,"height":640,"file":"2016\/10\/Unsponsored-Rescue-Essentials-2-1.jpg","sizes":{"thumbnail":{"file":"Unsponsored-Rescue-Essentials-2-1-200x200.jpg","width":200,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1-200x200.jpg"},"medium":{"file":"Unsponsored-Rescue-Essentials-2-1-225x300.jpg","width":225,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1-225x300.jpg"},"full":{"file":"Unsponsored-Rescue-Essentials-2-1.jpg","width":480,"height":640,"mime_type":"image\/jpeg","source_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1.jpg"}},"image_meta":{"aperture":"2.2","credit":"","camera":"iPhone 6s","caption":"","created_timestamp":"1456746717","copyright":"","focal_length":"4.15","iso":"25","shutter_speed":"0.013888888888889","title":"","orientation":"1","keywords":[]}},"post":20985,"source_url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Unsponsored-Rescue-Essentials-2-1.jpg","filename":"Unsponsored-Rescue-Essentials-2-1.jpg","filesize":125279,"_links":{"self":[{"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/media\/23639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/comments?post=23639"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":20985,"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/posts\/20985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}