{"id":23488,"date":"2016-10-06T20:36:53","date_gmt":"2016-10-06T19:36:53","guid":{"rendered":"http:\/\/www.unsponsored.co.uk\/press\/?p=23488"},"modified":"2016-10-06T20:36:53","modified_gmt":"2016-10-06T19:36:53","slug":"paddleexpo-2016-palm-equipment","status":"publish","type":"post","link":"https:\/\/www.unsponsored.co.uk\/press\/paddleexpo-2016-palm-equipment\/","title":{"rendered":"PaddleExpo 2016 With Palm Equipment"},"content":{"rendered":"<p>Palm equipment are launching a fair new pieces of gear at PaddleExpo this year.  This includes some new neoflex and safety gear.  Get a sneak peak with Cheesy.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"23489\" data-permalink=\"https:\/\/www.unsponsored.co.uk\/press\/paddleexpo-2016-palm-equipment\/screen-shot-2016-10-06-at-20-33-51\/\" data-orig-file=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Screen-Shot-2016-10-06-at-20.33.51.png\" data-orig-size=\"793,407\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"PaddleExpo 2016 With Palm Equipment\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Screen-Shot-2016-10-06-at-20.33.51.png\" src=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Screen-Shot-2016-10-06-at-20.33.51.png\" alt=\"PaddleExpo 2016 With Palm Equipment\" width=\"793\" height=\"407\" class=\"aligncenter size-full wp-image-23489\" srcset=\"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Screen-Shot-2016-10-06-at-20.33.51.png 793w, https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Screen-Shot-2016-10-06-at-20.33.51-300x154.png 300w, https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Screen-Shot-2016-10-06-at-20.33.51-768x394.png 768w, https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Screen-Shot-2016-10-06-at-20.33.51-676x347.png 676w\" sizes=\"auto, (max-width: 793px) 100vw, 793px\" \/><\/p>\n<p>Can you spot the new throw bag?<\/p>\n<p><!--more--><\/p>\n<p>Welcome to PaddleExpo 2016! Europe&#8217;s annual paddlesport trade show kicks off tomorrow, so stay posted for new products and show updates from Palm!<\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"http:\/\/www.youtube.com\/embed\/Ebq2Qb0bcqE?list=PLWWSUSMfVzH0bD4fkiL6c-eqbF_qZ5oH9\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Palm equipment are launching a fair new pieces of gear at PaddleExpo this year. This includes some new neoflex and safety gear. Get a sneak peak with Cheesy. Can you spot the new throw bag?<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[1896,5500,5501,826,5499,108],"class_list":["post-23488","post","type-post","status-publish","format-standard","hentry","category-gear","tag-germany","tag-nuremburg","tag-paddle-sports","tag-paddle-expo","tag-paddleexpo-2016-with-palm-equipment","tag-palm"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PaddleExpo 2016 With Palm Equipment - Unsponsored<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unsponsored.co.uk\/press\/paddleexpo-2016-palm-equipment\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PaddleExpo 2016 With Palm Equipment - Unsponsored\" \/>\n<meta property=\"og:description\" content=\"Palm equipment are launching a fair new pieces of gear at PaddleExpo this year. This includes some new neoflex and safety gear. Get a sneak peak with Cheesy. Can you spot the new throw bag?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unsponsored.co.uk\/press\/paddleexpo-2016-palm-equipment\/\" \/>\n<meta property=\"og:site_name\" content=\"Unsponsored\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-06T19:36:53+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Screen-Shot-2016-10-06-at-20.33.51.png\" \/>\n<meta name=\"author\" content=\"Unsponsored\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Unsponsored\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/paddleexpo-2016-palm-equipment\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/paddleexpo-2016-palm-equipment\\\/\"},\"author\":{\"name\":\"Unsponsored\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#\\\/schema\\\/person\\\/ce92703784b5b380a7ccd2c12e0231a5\"},\"headline\":\"PaddleExpo 2016 With Palm Equipment\",\"datePublished\":\"2016-10-06T19:36:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/paddleexpo-2016-palm-equipment\\\/\"},\"wordCount\":62,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#\\\/schema\\\/person\\\/ce92703784b5b380a7ccd2c12e0231a5\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/paddleexpo-2016-palm-equipment\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Screen-Shot-2016-10-06-at-20.33.51.png\",\"keywords\":[\"Germany\",\"Nuremburg\",\"Paddle Sports\",\"paddle-expo\",\"PaddleExpo 2016 With Palm Equipment\",\"Palm\"],\"articleSection\":[\"Gear\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/paddleexpo-2016-palm-equipment\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/paddleexpo-2016-palm-equipment\\\/\",\"url\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/paddleexpo-2016-palm-equipment\\\/\",\"name\":\"PaddleExpo 2016 With Palm Equipment - Unsponsored\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/paddleexpo-2016-palm-equipment\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/paddleexpo-2016-palm-equipment\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Screen-Shot-2016-10-06-at-20.33.51.png\",\"datePublished\":\"2016-10-06T19:36:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/paddleexpo-2016-palm-equipment\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/paddleexpo-2016-palm-equipment\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/paddleexpo-2016-palm-equipment\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Screen-Shot-2016-10-06-at-20.33.51.png\",\"contentUrl\":\"http:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Screen-Shot-2016-10-06-at-20.33.51.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/paddleexpo-2016-palm-equipment\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PaddleExpo 2016 With Palm Equipment\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#website\",\"url\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/\",\"name\":\"Unsponsored\",\"description\":\"Paddling tips, tricks, news and gear reviews from an Unsponsored point of view\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#\\\/schema\\\/person\\\/ce92703784b5b380a7ccd2c12e0231a5\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/#\\\/schema\\\/person\\\/ce92703784b5b380a7ccd2c12e0231a5\",\"name\":\"Unsponsored\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Viking-Banner-e1771869893655.png\",\"url\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Viking-Banner-e1771869893655.png\",\"contentUrl\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Viking-Banner-e1771869893655.png\",\"width\":163,\"height\":177,\"caption\":\"Unsponsored\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Viking-Banner-e1771869893655.png\"},\"url\":\"https:\\\/\\\/www.unsponsored.co.uk\\\/press\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PaddleExpo 2016 With Palm Equipment - Unsponsored","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unsponsored.co.uk\/press\/paddleexpo-2016-palm-equipment\/","og_locale":"en_GB","og_type":"article","og_title":"PaddleExpo 2016 With Palm Equipment - Unsponsored","og_description":"Palm equipment are launching a fair new pieces of gear at PaddleExpo this year. This includes some new neoflex and safety gear. Get a sneak peak with Cheesy. Can you spot the new throw bag?","og_url":"https:\/\/www.unsponsored.co.uk\/press\/paddleexpo-2016-palm-equipment\/","og_site_name":"Unsponsored","article_published_time":"2016-10-06T19:36:53+00:00","og_image":[{"url":"http:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Screen-Shot-2016-10-06-at-20.33.51.png","type":"","width":"","height":""}],"author":"Unsponsored","twitter_misc":{"Written by":"Unsponsored"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unsponsored.co.uk\/press\/paddleexpo-2016-palm-equipment\/#article","isPartOf":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/paddleexpo-2016-palm-equipment\/"},"author":{"name":"Unsponsored","@id":"https:\/\/www.unsponsored.co.uk\/press\/#\/schema\/person\/ce92703784b5b380a7ccd2c12e0231a5"},"headline":"PaddleExpo 2016 With Palm Equipment","datePublished":"2016-10-06T19:36:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/paddleexpo-2016-palm-equipment\/"},"wordCount":62,"commentCount":0,"publisher":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/#\/schema\/person\/ce92703784b5b380a7ccd2c12e0231a5"},"image":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/paddleexpo-2016-palm-equipment\/#primaryimage"},"thumbnailUrl":"http:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Screen-Shot-2016-10-06-at-20.33.51.png","keywords":["Germany","Nuremburg","Paddle Sports","paddle-expo","PaddleExpo 2016 With Palm Equipment","Palm"],"articleSection":["Gear"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.unsponsored.co.uk\/press\/paddleexpo-2016-palm-equipment\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.unsponsored.co.uk\/press\/paddleexpo-2016-palm-equipment\/","url":"https:\/\/www.unsponsored.co.uk\/press\/paddleexpo-2016-palm-equipment\/","name":"PaddleExpo 2016 With Palm Equipment - Unsponsored","isPartOf":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/paddleexpo-2016-palm-equipment\/#primaryimage"},"image":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/paddleexpo-2016-palm-equipment\/#primaryimage"},"thumbnailUrl":"http:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Screen-Shot-2016-10-06-at-20.33.51.png","datePublished":"2016-10-06T19:36:53+00:00","breadcrumb":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/paddleexpo-2016-palm-equipment\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unsponsored.co.uk\/press\/paddleexpo-2016-palm-equipment\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.unsponsored.co.uk\/press\/paddleexpo-2016-palm-equipment\/#primaryimage","url":"http:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Screen-Shot-2016-10-06-at-20.33.51.png","contentUrl":"http:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2016\/10\/Screen-Shot-2016-10-06-at-20.33.51.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unsponsored.co.uk\/press\/paddleexpo-2016-palm-equipment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unsponsored.co.uk\/press\/"},{"@type":"ListItem","position":2,"name":"PaddleExpo 2016 With Palm Equipment"}]},{"@type":"WebSite","@id":"https:\/\/www.unsponsored.co.uk\/press\/#website","url":"https:\/\/www.unsponsored.co.uk\/press\/","name":"Unsponsored","description":"Paddling tips, tricks, news and gear reviews from an Unsponsored point of view","publisher":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/#\/schema\/person\/ce92703784b5b380a7ccd2c12e0231a5"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unsponsored.co.uk\/press\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/www.unsponsored.co.uk\/press\/#\/schema\/person\/ce92703784b5b380a7ccd2c12e0231a5","name":"Unsponsored","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2020\/03\/Viking-Banner-e1771869893655.png","url":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2020\/03\/Viking-Banner-e1771869893655.png","contentUrl":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2020\/03\/Viking-Banner-e1771869893655.png","width":163,"height":177,"caption":"Unsponsored"},"logo":{"@id":"https:\/\/www.unsponsored.co.uk\/press\/wp-content\/uploads\/2020\/03\/Viking-Banner-e1771869893655.png"},"url":"https:\/\/www.unsponsored.co.uk\/press\/author\/admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p2ugbA-66Q","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/posts\/23488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/comments?post=23488"}],"version-history":[{"count":1,"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/posts\/23488\/revisions"}],"predecessor-version":[{"id":23490,"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/posts\/23488\/revisions\/23490"}],"wp:attachment":[{"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/media?parent=23488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/categories?post=23488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unsponsored.co.uk\/press\/wp-json\/wp\/v2\/tags?post=23488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}